{"id":379715,"date":"2026-05-13T16:00:00","date_gmt":"2026-05-13T19:00:00","guid":{"rendered":"https:\/\/jundiai.sp.gov.br\/noticias\/?p=379715"},"modified":"2026-05-13T13:45:55","modified_gmt":"2026-05-13T16:45:55","slug":"pontojovem-aposta-no-desenvolvimento-de-jovens-para-o-mercado-e-para-a-vida","status":"publish","type":"post","link":"https:\/\/jundiai.sp.gov.br\/noticias\/2026\/05\/13\/pontojovem-aposta-no-desenvolvimento-de-jovens-para-o-mercado-e-para-a-vida\/","title":{"rendered":"Ponto+Jovem aposta no desenvolvimento de jovens para o mercado e para a vida"},"content":{"rendered":"\n<p>Um espa\u00e7o pensado para acolher, inspirar e preparar os jovens para o futuro. Assim \u00e9 o Ponto+Jovem, iniciativa da Prefeitura de Jundia\u00ed, por meio da Casa Civil e da Assessoria de Pol\u00edticas para a Juventude, em parceria com a Funda\u00e7\u00e3o TVTEC. O programa oferece aos adolescentes a oportunidade de experimentar novas \u00e1reas, desenvolver habilidades, trocar experi\u00eancias e ganhar mais confian\u00e7a para ingressar no mercado de trabalho.<\/p>\n\n\n\n<p>Entre as atividades promovidas est\u00e3o oficinas e forma\u00e7\u00f5es nas \u00e1reas de tecnologia, comunica\u00e7\u00e3o, produ\u00e7\u00e3o de conte\u00fado, cultura e desenvolvimento pessoal, contribuindo tanto para a escolha de uma carreira quanto para o fortalecimento da autoestima e da express\u00e3o dos participantes.<\/p>\n\n\n\n<p>Foi nesse ambiente de aprendizado e criatividade que a jovem Larissa Santanna Duarte Silva, de 16 anos, participou da oficina de orat\u00f3ria promovida pelo programa. Como muitos adolescentes, ela convivia com o nervosismo ao falar em p\u00fablico e viu na atividade uma oportunidade de superar esse desafio.<\/p>\n\n\n\n<p>A oficina, conduzida pelo professor Silvio Rom\u00e3o, reuniu cerca de 30 adolescentes da Guardinha (Associa\u00e7\u00e3o de Educa\u00e7\u00e3o do Homem de Amanh\u00e3) em uma aula din\u00e2mica, descontra\u00edda e com linguagem pr\u00f3xima dos jovens. Durante a atividade, os participantes receberam orienta\u00e7\u00f5es sobre comunica\u00e7\u00e3o, express\u00e3o e confian\u00e7a ao falar. \u201cCom certeza agora vou conseguir me comunicar melhor\u201d, afirmou Larissa ap\u00f3s a experi\u00eancia.<\/p>\n\n\n\n<p>Levi Pompermayer Salles, 18, tamb\u00e9m aproveitou as dicas. \u201cSempre tive vergonha de interagir com as pessoas, e com o que o professor nos passou, vou conseguir lidar melhor com o medo e transmitir a mensagem que eu preciso.\u201d<\/p>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-9d6595d7 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1280\" height=\"854\" src=\"https:\/\/jundiai.sp.gov.br\/noticias\/wp-content\/uploads\/sites\/32\/2026\/05\/ponto_mais_jovem_tv_tec-1-1280x854.jpg\" alt=\"\" class=\"wp-image-379728\" srcset=\"https:\/\/jundiai.sp.gov.br\/noticias\/wp-content\/uploads\/sites\/32\/2026\/05\/ponto_mais_jovem_tv_tec-1-1280x854.jpg 1280w, https:\/\/jundiai.sp.gov.br\/noticias\/wp-content\/uploads\/sites\/32\/2026\/05\/ponto_mais_jovem_tv_tec-1-300x200.jpg 300w, https:\/\/jundiai.sp.gov.br\/noticias\/wp-content\/uploads\/sites\/32\/2026\/05\/ponto_mais_jovem_tv_tec-1-768x512.jpg 768w, https:\/\/jundiai.sp.gov.br\/noticias\/wp-content\/uploads\/sites\/32\/2026\/05\/ponto_mais_jovem_tv_tec-1-1536x1024.jpg 1536w, https:\/\/jundiai.sp.gov.br\/noticias\/wp-content\/uploads\/sites\/32\/2026\/05\/ponto_mais_jovem_tv_tec-1-450x300.jpg 450w, https:\/\/jundiai.sp.gov.br\/noticias\/wp-content\/uploads\/sites\/32\/2026\/05\/ponto_mais_jovem_tv_tec-1.jpg 1900w\" sizes=\"auto, (max-width: 1280px) 100vw, 1280px\" \/><figcaption class=\"wp-element-caption\">Forma\u00e7\u00e3o em orat\u00f3ria foi direcionada a jovens da Guardinha<\/figcaption><\/figure>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1280\" height=\"853\" src=\"https:\/\/jundiai.sp.gov.br\/noticias\/wp-content\/uploads\/sites\/32\/2026\/05\/ponto_mais_jovem_tv_tec-37-1280x853.jpg\" alt=\"\" class=\"wp-image-379729\" srcset=\"https:\/\/jundiai.sp.gov.br\/noticias\/wp-content\/uploads\/sites\/32\/2026\/05\/ponto_mais_jovem_tv_tec-37-1280x853.jpg 1280w, https:\/\/jundiai.sp.gov.br\/noticias\/wp-content\/uploads\/sites\/32\/2026\/05\/ponto_mais_jovem_tv_tec-37-300x200.jpg 300w, https:\/\/jundiai.sp.gov.br\/noticias\/wp-content\/uploads\/sites\/32\/2026\/05\/ponto_mais_jovem_tv_tec-37-768x512.jpg 768w, https:\/\/jundiai.sp.gov.br\/noticias\/wp-content\/uploads\/sites\/32\/2026\/05\/ponto_mais_jovem_tv_tec-37-1536x1023.jpg 1536w, https:\/\/jundiai.sp.gov.br\/noticias\/wp-content\/uploads\/sites\/32\/2026\/05\/ponto_mais_jovem_tv_tec-37-450x300.jpg 450w, https:\/\/jundiai.sp.gov.br\/noticias\/wp-content\/uploads\/sites\/32\/2026\/05\/ponto_mais_jovem_tv_tec-37.jpg 1900w\" sizes=\"auto, (max-width: 1280px) 100vw, 1280px\" \/><figcaption class=\"wp-element-caption\">Levi, 18, aproveitou as dicas da aula <\/figcaption><\/figure>\n<\/div>\n<\/div>\n\n\n\n<p>Para acompanhar a programa\u00e7\u00e3o de cursos e oficinas, os interessados devem ficar atentos \u00e0 agenda da Funda\u00e7\u00e3o TVTEC. Mais informa\u00e7\u00f5es e inscri\u00e7\u00f5es podem ser feitas pelos canais oficiais da TVTEC, inclusive pelo WhatsApp (11) 99729-4044.<\/p>\n\n\n\n<p><strong>Assessoria de Imprensa<br>Fotos: Fot\u00f3grafos PMJ<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Um espa\u00e7o pensado para acolher, inspirar e preparar os jovens para o futuro. Assim \u00e9 o Ponto+Jovem, iniciativa da Prefeitura de Jundia\u00ed, por meio da Casa Civil e da Assessoria de Pol\u00edticas para a Juventude, em parceria com a Funda\u00e7\u00e3o TVTEC. O programa oferece aos adolescentes a oportunidade de experimentar novas \u00e1reas, desenvolver habilidades, trocar [&hellip;]<\/p>\n","protected":false},"author":133,"featured_media":379726,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4620,2],"tags":[991,62],"ods":[],"class_list":["post-379715","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-destaques","category-noticias","tag-assessoria-de-politicas-para-a-juventude","tag-casa-civil"],"_links":{"self":[{"href":"https:\/\/jundiai.sp.gov.br\/noticias\/wp-json\/wp\/v2\/posts\/379715","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/jundiai.sp.gov.br\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/jundiai.sp.gov.br\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/jundiai.sp.gov.br\/noticias\/wp-json\/wp\/v2\/users\/133"}],"replies":[{"embeddable":true,"href":"https:\/\/jundiai.sp.gov.br\/noticias\/wp-json\/wp\/v2\/comments?post=379715"}],"version-history":[{"count":4,"href":"https:\/\/jundiai.sp.gov.br\/noticias\/wp-json\/wp\/v2\/posts\/379715\/revisions"}],"predecessor-version":[{"id":379765,"href":"https:\/\/jundiai.sp.gov.br\/noticias\/wp-json\/wp\/v2\/posts\/379715\/revisions\/379765"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/jundiai.sp.gov.br\/noticias\/wp-json\/wp\/v2\/media\/379726"}],"wp:attachment":[{"href":"https:\/\/jundiai.sp.gov.br\/noticias\/wp-json\/wp\/v2\/media?parent=379715"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/jundiai.sp.gov.br\/noticias\/wp-json\/wp\/v2\/categories?post=379715"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/jundiai.sp.gov.br\/noticias\/wp-json\/wp\/v2\/tags?post=379715"},{"taxonomy":"ods","embeddable":true,"href":"https:\/\/jundiai.sp.gov.br\/noticias\/wp-json\/wp\/v2\/ods?post=379715"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}